{"id":142233,"date":"2020-10-30T12:50:45","date_gmt":"2020-10-30T12:50:45","guid":{"rendered":"https:\/\/central-asia.guide\/ouzbekistan\/destinations-en-ouzbekistan\/observatoire-de-maidanak\/"},"modified":"2026-01-17T10:13:14","modified_gmt":"2026-01-17T10:13:14","slug":"observatoire-de-maidanak","status":"publish","type":"page","link":"https:\/\/central-asia.guide\/fr\/ouzbekistan\/destinations-en-ouzbekistan\/observatoire-de-maidanak\/","title":{"rendered":"Observatoire de Maidanak"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"142233\" class=\"elementor elementor-142233 elementor-3835\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-993cc5b e-con-full e-flex e-con e-parent\" data-id=\"993cc5b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3474d72 elementor-widget elementor-widget-heading\" data-id=\"3474d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Observatoire de Maidanak<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52474b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52474b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aff150\" data-id=\"3aff150\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec4fe55 elementor-widget elementor-widget-spacer\" data-id=\"ec4fe55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e79d79a elementor-widget elementor-widget-heading\" data-id=\"e79d79a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Observatoire de Maidanak<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aa8465 elementor-widget elementor-widget-text-editor\" data-id=\"7aa8465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;observatoire de Maidanak (ou Maydanak) fait partie du complexe de l&rsquo;observatoire astronomique de haute altitude de Kitab, construit en 1970. Il est situ\u00e9 dans la partie ouest du plateau de Maidanak, \u00e0 45 km au sud de <a href=\"https:\/\/central-asia.guide\/fr\/ouzbekistan\/destinations-en-ouzbekistan\/shahrisabz\/\">Shakhrisabz<\/a>, sur la montagne de Kitab, au sud de la ville de Kutab. La superficie totale de l&rsquo;observatoire est d&rsquo;environ 32 hectares. Les instruments les plus importants de l&rsquo;observatoire sont des t\u00e9lescopes \u00e0 miroir modernes AZT-22 (avec un diam\u00e8tre de miroir de 1,5 m\u00e8tre) et un t\u00e9lescope de Carl Zeiss-Jena (avec un diam\u00e8tre de miroir de 1 m\u00e8tre). Il y a en fait deux stations d&rsquo;observation distinctes dans la r\u00e9gion et les<span style=\"font-size: 16px; font-style: normal; font-weight: 400;\">touristes peuvent entrer dans la partie ouest o\u00f9 se trouvent tous les objets astronomiques civils.<\/span>    <\/p><p>Au d\u00e9but des ann\u00e9es 1970, l&rsquo;observatoire de Maydanak a \u00e9t\u00e9 exploit\u00e9 comme station satellite sovi\u00e9tique d&rsquo;examen des lasers. Cependant, les astronomes de l&rsquo;Institut astronomique <a href=\"https:\/\/central-asia.guide\/fr\/ouzbekistan\/culture-ouzbeke\/le-peuple-ouzbek\/ulugh-beg\/\">Mirzo Ulugbek<\/a> ont \u00e9t\u00e9 autoris\u00e9s \u00e0 poursuivre leurs observations astronomiques \u00e0 l&rsquo;aide de deux t\u00e9lescopes de 60 centim\u00e8tres et d&rsquo;un t\u00e9lescope de 48 centim\u00e8tres situ\u00e9s \u00e0 proximit\u00e9 de la station. Pendant ce temps, l&rsquo;Institut d&rsquo;astronomie de l&rsquo;Universit\u00e9 d&rsquo;\u00c9tat de Moscou, qui porte le nom de Sternberg, et plusieurs autres institutions de l&rsquo;Union sovi\u00e9tique ont install\u00e9 leurs objets astronomiques sur un sommet voisin, situ\u00e9 \u00e0 5 km \u00e0 l&rsquo;ouest du mont Maidanak. Depuis 1996, l&rsquo;observatoire astronomique de Maidanak participe \u00e0 plusieurs programmes internationaux d&rsquo;observation et de recherche.     <\/p><p>Les travaux sont men\u00e9s dans le cadre d&rsquo;accords bilat\u00e9raux entre l&rsquo;Institut astronomique Mirzo Ulugbek et des institutions astronomiques russes, ukrainiennes, am\u00e9ricaines, allemandes, fran\u00e7aises, italiennes, japonaises, cor\u00e9ennes, ta\u00efwanaises et d&rsquo;autres encore.  <span style=\"font-size: 16px;\">Le nombre de partenaires de l&rsquo;observatoire astronomique de Maidanak ayant consid\u00e9rablement augment\u00e9 en 2005, il est apparu n\u00e9cessaire de coordonner les programmes et les efforts des diff\u00e9rentes organisations dans le cadre des activit\u00e9s de l&rsquo;observatoire. Aujourd&rsquo;hui, l&rsquo;Observatoire de Misanak est devenu une v\u00e9ritable organisation internationale, dont les activit\u00e9s scientifiques et les th\u00e8mes prioritaires sont s\u00e9lectionn\u00e9s en fonction de la coordination de la communaut\u00e9 des utilisateurs de Maidanak. La communaut\u00e9 joue \u00e9galement un r\u00f4le important en fournissant \u00e0 l&rsquo;Observatoire astronomique de Misanak des outils et des mises \u00e0 niveau de t\u00e9lescopes. Elle apporte \u00e9galement son soutien \u00e0 la mise \u00e0 niveau de son infrastructure.   <\/span><\/p><p>Il existe peu d&rsquo;endroits dans l&rsquo;h\u00e9misph\u00e8re nord o\u00f9 les observations astronomiques peuvent \u00eatre r\u00e9alis\u00e9es avec autant de clart\u00e9 qu&rsquo;ici. Les nuits sont claires et propres, ce qui permet de mener un grand nombre de programmes d&rsquo;observation. L&rsquo;observatoire de Maidanak est unique en raison de sa situation g\u00e9ographique, \u00e0 mi-chemin entre les principaux objets astronomiques du monde, les \u00eeles Canaries et Hawa\u00ef, ainsi que de ses conditions atmosph\u00e9riques de grande qualit\u00e9 (astroclimat). Cela fait de Maidanak un lieu particuli\u00e8rement utile pour divers programmes d&rsquo;observation qui n\u00e9cessitent une surveillance constante des objets astrophysiques.     <span style=\"font-size: 16px;\">Le nombre d&rsquo;heures de clart\u00e9 nocturne et leur r\u00e9partition par saison pour l&rsquo;observatoire de Maidanak sont typiques des montagnes d&rsquo;Asie centrale. Il repr\u00e9sente environ 58 % de la p\u00e9riode annuelle d&rsquo;obscurit\u00e9, soit 2 000 heures. Cela signifie que la capacit\u00e9 d&rsquo;observation estivale de l&rsquo;observatoire de Maidanak est deux fois plus \u00e9lev\u00e9e qu&rsquo;en hiver (environ 90 % en juillet et jusqu&rsquo;\u00e0 50 % en f\u00e9vrier).    <\/span><\/p><p><span style=\"font-size: 16px;\">Le plateau de Maidanak est id\u00e9al pour l&rsquo;observation et l&rsquo;\u00e9tude du ciel nocturne. Sur le sommet occidental du plateau se trouve un autre objet : une station militaire. Elle assure le suivi des engins spatiaux.   <\/span>Les conditions climatiques sur le plateau sont assez rudes car elles sont adapt\u00e9es \u00e0 l&rsquo;environnement de haute montagne. Le vent y souffle et il y fait plut\u00f4t froid en hiver, tandis qu&rsquo;en \u00e9t\u00e9, il est difficile de supporter le soleil aux rayons anormalement br\u00fblants. <\/p><p>Plus d&rsquo;informations sur le <a href=\"http:\/\/www.maidanak.uz\/\">site officiel de l&rsquo;observatoire de Maidanak<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0e172c elementor-widget elementor-widget-text-editor\" data-id=\"d0e172c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"ast-breadcrumbs-wrapper\">\n\t\t\t<div class=\"ast-breadcrumbs-inner\"><nav role=\"navigation\" aria-label=\"Breadcrumbs\" class=\"breadcrumb-trail breadcrumbs\" ><div class=\"ast-breadcrumbs\"><ul class=\"trail-items\" ><li  class=\"trail-item trail-end\"><span><a href=\"https:\/\/central-asia.guide\/fr\/\" rel=\"home\"><span >Accueil<\/span><\/a><\/span><\/li><\/ul><\/div><\/nav><\/div>\n\t\t<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad50f0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7ad50f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69fc250 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69fc250\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-195d34a\" data-id=\"195d34a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0c9f1a elementor-widget elementor-widget-google_maps\" data-id=\"a0c9f1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=maidanak%20observatory&#038;t=m&#038;z=9&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"maidanak observatory\"\n\t\t\t\t\taria-label=\"maidanak observatory\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f782af1 elementor-widget elementor-widget-spacer\" data-id=\"f782af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf9101 elementor-widget elementor-widget-heading\" data-id=\"cbf9101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Autres curiosit\u00e9s et destinations \u00e0 proximit\u00e9 de l'observatoire Maidanak<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7349249 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7349249\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3871b17\" data-id=\"3871b17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a94b087 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"a94b087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/central-asia.guide\/fr\/ouzbekistan\/destinations-en-ouzbekistan\/shahrisabz\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/central-asia.guide\/wp-content\/uploads\/2022\/01\/Shahrisabz_Dorut_tilavat_Kok_Gumbaz_mosque_Uzbekistan-768x512.jpg);\" role=\"img\" aria-label=\"Shahrisabz Dorut Tilavat\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tShahrisabz\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tCliquez ici\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4743a61\" data-id=\"4743a61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-045d30f elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"045d30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/central-asia.guide\/fr\/ouzbekistan\/destinations-en-ouzbekistan\/shahrisabz\/qarshi\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/central-asia.guide\/wp-content\/uploads\/2021\/09\/Qarshi_amira_temura_bridge_uzbekistan-768x403.jpg);\" role=\"img\" aria-label=\"Pont Amir Temur sur la rivi\u00e8re Kashkadarya \u00e0 Qarshi, Ouzb\u00e9kistan\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tQarshi\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tCliquez ici\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3488889\" data-id=\"3488889\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ad1d21 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"3ad1d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/central-asia.guide\/fr\/ouzbekistan\/destinations-en-ouzbekistan\/grotte-de-boybuloq\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/central-asia.guide\/wp-content\/uploads\/2021\/02\/Boybuloq-Cave.jpg);\" role=\"img\" aria-label=\"Grotte de Boybuloq\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tGrotte de Boybuloq\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tCliquez ici\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13c6a18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13c6a18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1846cad\" data-id=\"1846cad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9a8c38 elementor-widget elementor-widget-text-editor\" data-id=\"c9a8c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>Page mise \u00e0 jour le 3.1.2021<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4490e elementor-widget elementor-widget-spacer\" data-id=\"6d4490e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Observatoire de Maidanak Observatoire de Maidanak L&rsquo;observatoire de Maidanak (ou Maydanak) fait partie du complexe de l&rsquo;observatoire astronomique de haute altitude de Kitab, construit en 1970. Il est situ\u00e9 dans la partie ouest du plateau de Maidanak, \u00e0 45 km au sud de Shakhrisabz, sur la montagne de Kitab, au sud de la ville de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":129723,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[],"tour_type":[],"private_group":[],"duration":[],"time-period":[],"starting-point":[],"starting-price":[],"countries":[],"sight":[],"class_list":["post-142233","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/pages\/142233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/comments?post=142233"}],"version-history":[{"count":7,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/pages\/142233\/revisions"}],"predecessor-version":[{"id":176668,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/pages\/142233\/revisions\/176668"}],"up":[{"embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/pages\/129723"}],"wp:attachment":[{"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/media?parent=142233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/categories?post=142233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/tags?post=142233"},{"taxonomy":"tour_type","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/tour_type?post=142233"},{"taxonomy":"private_group","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/private_group?post=142233"},{"taxonomy":"duration","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/duration?post=142233"},{"taxonomy":"time-period","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/time-period?post=142233"},{"taxonomy":"starting-point","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/starting-point?post=142233"},{"taxonomy":"starting-price","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/starting-price?post=142233"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/countries?post=142233"},{"taxonomy":"sight","embeddable":true,"href":"https:\/\/central-asia.guide\/fr\/wp-json\/wp\/v2\/sight?post=142233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}